{"id":6473,"date":"2021-01-25T11:01:25","date_gmt":"2021-01-25T11:01:25","guid":{"rendered":"https:\/\/mericonline.com\/?page_id=6473"},"modified":"2021-04-06T13:07:23","modified_gmt":"2021-04-06T11:07:23","slug":"services-social-network-portal","status":"publish","type":"page","link":"https:\/\/mericonline.com\/ar\/services-social-network-portal\/","title":{"rendered":"\u0627\u0644\u062e\u062f\u0645\u0627\u062a - \u0628\u0648\u0627\u0628\u0629 \u0627\u0644\u0634\u0628\u0643\u0629 \u0627\u0644\u0627\u062c\u062a\u0645\u0627\u0639\u064a\u0629"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6473\" class=\"elementor elementor-6473\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0ee7c64 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0ee7c64\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8fa1f41\" data-id=\"8fa1f41\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-87ed860 elementor-widget elementor-widget-heading\" data-id=\"87ed860\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Keep your organization connected, safe and secure<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b9e541c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b9e541c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e1e6e70\" data-id=\"e1e6e70\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8cf956 elementor-widget elementor-widget-text-editor\" data-id=\"e8cf956\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"MsoNormal\" style=\"line-height:150%\"><span style=\"font-size: 14pt; line-height: 150%; background-image: initial; background-position: initial; background-size: initial; background-repeat: initial; background-attachment: initial; background-origin: initial; background-clip: initial;\">We guarantee secure social networks restricted to your\norganization\u2019s individuals. Our social network portals are similar to regular\nsocial media channels yet more secure and confidential for your organization\u2019s\ninformation. Social networks&nbsp;help to streamline communication and increase\nthe morale and productivity of employees, so; Keep your corporate\u2019s or organizational\nnetwork connected, safe and secure.&nbsp;&nbsp;<o:p><\/o:p><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ab4aeb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ab4aeb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fe75e09\" data-id=\"fe75e09\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d79901 elementor-widget elementor-widget-Saasland_processes\" data-id=\"8d79901\" data-element_type=\"widget\" data-widget_type=\"Saasland_processes.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <section class=\"agency_featured_area\">\r\n                <div class=\"container\">\r\n                                            <h2 class=\"f_size_30 f_600 t_color3 l_height40 text-center wow fadeInUp\" data-wow-delay=\"0.3s\">\r\n                            <br \/>\n                        <\/h2>\r\n                                        <div class=\"features_info\">\r\n                                                    <img decoding=\"async\" class=\"dot_img\" src=\"https:\/\/mericonline.com\/wp-content\/plugins\/saasland-core\/widgets\/images\/dot_3_items.png\" alt=\"Shape\">\r\n                                                                                    <div class=\"row agency_featured_item elementor-repeater-item-0979933 flex-row-reverse\">\r\n                                    <div class=\"col-lg-6\">\r\n                                        <div class=\"agency_featured_img text-right wow fadeInRight\"\r\n                                             data-wow-delay=\"0.4s\">\r\n                                            <img fetchpriority=\"high\" decoding=\"async\" width=\"348\" height=\"350\" src=\"https:\/\/mericonline.com\/wp-content\/uploads\/2021\/01\/security.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mericonline.com\/wp-content\/uploads\/2021\/01\/security.png 348w, https:\/\/mericonline.com\/wp-content\/uploads\/2021\/01\/security-100x100.png 100w, https:\/\/mericonline.com\/wp-content\/uploads\/2021\/01\/security-298x300.png 298w, https:\/\/mericonline.com\/wp-content\/uploads\/2021\/01\/security-150x150.png 150w, https:\/\/mericonline.com\/wp-content\/uploads\/2021\/01\/security-80x80.png 80w, https:\/\/mericonline.com\/wp-content\/uploads\/2021\/01\/security-70x70.png 70w, https:\/\/mericonline.com\/wp-content\/uploads\/2021\/01\/security-75x75.png 75w\" sizes=\"(max-width: 348px) 100vw, 348px\" \/>                                        <\/div>\r\n                                    <\/div>\r\n                                    <div class=\"col-lg-6\">\r\n                                        <div class=\"agency_featured_content pr_70 pl_70 wow fadeInLeft\"\r\n                                             data-wow-delay=\"0.6s\">\r\n                                            <div class=\"dot\"><span class=\"dot1\"><\/span><span class=\"dot2\"><\/span><\/div>\r\n                                                                                            <img decoding=\"async\" class=\"number\"\r\n                                                     src=\"https:\/\/mericonline.com\/wp-content\/plugins\/saasland-core\/widgets\/images\/numbers\/1.png\"\r\n                                                     alt=\"100% Safe and Secure\">\r\n                                                                                                                                            <h3> 100% Safe and Secure <\/h3>\r\n                                                                                                                                                                            <\/div>\r\n                                    <\/div>\r\n                                <\/div>\r\n                                                                <div class=\"row agency_featured_item elementor-repeater-item-727f51f agency_featured_item_two\">\r\n                                    <div class=\"col-lg-6\">\r\n                                        <div class=\"agency_featured_img text-right wow fadeInRight\"\r\n                                             data-wow-delay=\"0.4s\">\r\n                                            <img decoding=\"async\" width=\"177\" height=\"242\" src=\"https:\/\/mericonline.com\/wp-content\/uploads\/2019\/12\/women.png\" class=\"attachment-full size-full\" alt=\"\" \/>                                        <\/div>\r\n                                    <\/div>\r\n                                    <div class=\"col-lg-6\">\r\n                                        <div class=\"agency_featured_content pr_70 pl_100 wow fadeInLeft\"\r\n                                             data-wow-delay=\"0.6s\">\r\n                                            <div class=\"dot\"><span class=\"dot1\"><\/span><span class=\"dot2\"><\/span><\/div>\r\n                                                                                            <img decoding=\"async\" class=\"number\"\r\n                                                     src=\"https:\/\/mericonline.com\/wp-content\/plugins\/saasland-core\/widgets\/images\/numbers\/2.png\"\r\n                                                     alt=\"Internal Secured Chatting\">\r\n                                                                                                                                            <h3> Internal Secured Chatting <\/h3>\r\n                                                                                                                                                                            <\/div>\r\n                                    <\/div>\r\n                                <\/div>\r\n                                                                <div class=\"row agency_featured_item elementor-repeater-item-353d549 flex-row-reverse\">\r\n                                    <div class=\"col-lg-6\">\r\n                                        <div class=\"agency_featured_img text-right wow fadeInRight\"\r\n                                             data-wow-delay=\"0.4s\">\r\n                                            <img decoding=\"async\" width=\"650\" height=\"491\" src=\"https:\/\/mericonline.com\/wp-content\/uploads\/2020\/12\/consultancy2.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mericonline.com\/wp-content\/uploads\/2020\/12\/consultancy2.png 650w, https:\/\/mericonline.com\/wp-content\/uploads\/2020\/12\/consultancy2-300x227.png 300w, https:\/\/mericonline.com\/wp-content\/uploads\/2020\/12\/consultancy2-370x280.png 370w, https:\/\/mericonline.com\/wp-content\/uploads\/2020\/12\/consultancy2-634x480.png 634w, https:\/\/mericonline.com\/wp-content\/uploads\/2020\/12\/consultancy2-600x453.png 600w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>                                        <\/div>\r\n                                    <\/div>\r\n                                    <div class=\"col-lg-6\">\r\n                                        <div class=\"agency_featured_content pr_70 pl_70 wow fadeInLeft\"\r\n                                             data-wow-delay=\"0.6s\">\r\n                                            <div class=\"dot\"><span class=\"dot1\"><\/span><span class=\"dot2\"><\/span><\/div>\r\n                                                                                            <img decoding=\"async\" class=\"number\"\r\n                                                     src=\"https:\/\/mericonline.com\/wp-content\/plugins\/saasland-core\/widgets\/images\/numbers\/3.png\"\r\n                                                     alt=\"Sharing Important Updates \">\r\n                                                                                                                                            <h3> Sharing Important Updates  <\/h3>\r\n                                                                                                                                                                            <\/div>\r\n                                    <\/div>\r\n                                <\/div>\r\n                                                        <div class=\"dot middle_dot middle_dot4\"><span class=\"dot1\"><\/span><span\r\n                                    class=\"dot2\"><\/span><\/div>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/section>\r\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c62519d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c62519d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dbafec3\" data-id=\"dbafec3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7278c2d elementor-widget elementor-widget-heading\" data-id=\"7278c2d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Request a demo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a2f00ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a2f00ca\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d763b1e\" data-id=\"d763b1e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc70077 elementor-widget elementor-widget-wpforms\" data-id=\"cc70077\" data-element_type=\"widget\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-6000\"><form id=\"wpforms-form-6000\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"6000\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/ar\/wp-json\/wp\/v2\/pages\/6473\" data-token=\"791d521ed4b1870de4b26cf50a79a99c\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-page-indicator connector\" data-indicator=\"connector\" data-indicator-color=\"#118dde\" data-scroll=\"1\"><div class=\"wpforms-page-indicator-page active  wpforms-page-indicator-page-1\" style=\"width:50%;\"><span class=\"wpforms-page-indicator-page-number\" style=\"background-color:#118dde\">1<span class=\"wpforms-page-indicator-page-triangle\" style=\"border-top-color:#118dde\"><\/span><\/span><\/div><div class=\"wpforms-page-indicator-page  wpforms-page-indicator-page-2\" style=\"width:50%;\"><span class=\"wpforms-page-indicator-page-number\" >2<span class=\"wpforms-page-indicator-page-triangle\" ><\/span><\/span><\/div><\/div><div class=\"wpforms-field-container\"><div class=\"wpforms-page wpforms-page-1 \"><div id=\"wpforms-6000-field_6-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"6\"><\/div><div id=\"wpforms-6000-field_4-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-6000-field_4\">Username <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-6000-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" required><\/div><div id=\"wpforms-6000-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-6000-field_2\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"email\" id=\"wpforms-6000-field_2\" class=\"wpforms-field-required wpforms-field-email-primary\" name=\"wpforms[fields][2][primary]\" placeholder=\"Email\" required><label for=\"wpforms-6000-field_2\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Email<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"email\" id=\"wpforms-6000-field_2-secondary\" class=\"wpforms-field-email-secondary wpforms-field-required\" data-rule-confirm=\"#wpforms-6000-field_2\" name=\"wpforms[fields][2][secondary]\" placeholder=\"Confirm Email\" required><label for=\"wpforms-6000-field_2-secondary\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Confirm Email<\/label><\/div><\/div><\/div><div id=\"wpforms-6000-field_10-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"10\"><label class=\"wpforms-field-label\" for=\"wpforms-6000-field_10\">Please select which service would you like to test. <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-6000-field_10\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-6000-field_10_1\" name=\"wpforms[fields][10][]\" value=\"Federated Search Engine\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-6000-field_10_1\">Federated Search Engine<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-6000-field_10_2\" name=\"wpforms[fields][10][]\" value=\"Research Management Tools\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-6000-field_10_2\">Research Management Tools<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"checkbox\" id=\"wpforms-6000-field_10_8\" name=\"wpforms[fields][10][]\" value=\"Single Authentication Point\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-6000-field_10_8\">Single Authentication Point<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-6000-field_10_3\" name=\"wpforms[fields][10][]\" value=\"eBooks Portal\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-6000-field_10_3\">eBooks Portal<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-6000-field_10_4\" name=\"wpforms[fields][10][]\" value=\"eNews Portal\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-6000-field_10_4\">eNews Portal<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-6000-field_10_5\" name=\"wpforms[fields][10][]\" value=\"Library Management System (LMS)\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-6000-field_10_5\">Library Management System (LMS)<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-6000-field_10_6\" name=\"wpforms[fields][10][]\" value=\"eLearing Portal\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-6000-field_10_6\">eLearing Portal<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"checkbox\" id=\"wpforms-6000-field_10_7\" name=\"wpforms[fields][10][]\" value=\"Social Network Portal\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-6000-field_10_7\">Social Network Portal<\/label><\/li><\/ul><\/div><div id=\"wpforms-6000-field_5-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"5\"><div class=\"wpforms-clear wpforms-pagebreak-left\"><button class=\"wpforms-page-button wpforms-page-next\" data-action=\"next\" data-page=\"1\" data-formid=\"6000\" disabled>Next<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-2 last \" style=\"display:none;\"><div id=\"wpforms-6000-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-6000-field_1\">Name <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-6000-field_1\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][1][first]\" required><label for=\"wpforms-6000-field_1\" class=\"wpforms-field-sublabel after \">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-6000-field_1-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][1][last]\" required><label for=\"wpforms-6000-field_1-last\" class=\"wpforms-field-sublabel after \">Last<\/label><\/div><\/div><\/div><div id=\"wpforms-6000-field_8-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-6000-field_8\">Phone Number <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-6000-field_8\" class=\"wpforms-field-medium wpforms-field-required wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][8]\" required><\/div><div id=\"wpforms-6000-field_11-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"11\"><label class=\"wpforms-field-label\" for=\"wpforms-6000-field_11\">Profession <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-6000-field_11\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][11]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>Select profession<\/option><option value=\"Professor\" >Professor<\/option><option value=\"Student\" >Student<\/option><option value=\"Researcher\" >Researcher<\/option><option value=\"Librarian\" >Librarian<\/option><option value=\"R &amp; D Specialist\" >R &amp; D Specialist<\/option><option value=\"Other\" >Other<\/option><\/select><\/div><div id=\"wpforms-6000-field_9-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-6000-field_9\">Country <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-6000-field_9\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][9]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>Select Country<\/option><option value=\"Afghanistan\" >Afghanistan<\/option><option value=\"Albania\" >Albania<\/option><option value=\"Algeria\" >Algeria<\/option><option value=\"American Samoa\" >American Samoa<\/option><option value=\"Andorra\" >Andorra<\/option><option value=\"Angola\" >Angola<\/option><option value=\"Anguilla\" >Anguilla<\/option><option value=\"Antarctica\" >Antarctica<\/option><option value=\"Antigua and Barbuda\" >Antigua and Barbuda<\/option><option value=\"Argentina\" >Argentina<\/option><option value=\"Armenia\" >Armenia<\/option><option value=\"Aruba\" >Aruba<\/option><option value=\"Australia\" >Australia<\/option><option value=\"Austria\" >Austria<\/option><option value=\"Azerbaijan\" >Azerbaijan<\/option><option value=\"Bahamas\" >Bahamas<\/option><option value=\"Bahrain\" >Bahrain<\/option><option value=\"Bangladesh\" >Bangladesh<\/option><option value=\"Barbados\" >Barbados<\/option><option value=\"Belarus\" >Belarus<\/option><option value=\"Belgium\" >Belgium<\/option><option value=\"Belize\" >Belize<\/option><option value=\"Benin\" >Benin<\/option><option value=\"Bermuda\" >Bermuda<\/option><option value=\"Bhutan\" >Bhutan<\/option><option value=\"Bolivia (Plurinational State of)\" >Bolivia (Plurinational State of)<\/option><option value=\"Bosnia and Herzegovina\" >Bosnia and Herzegovina<\/option><option value=\"Botswana\" >Botswana<\/option><option value=\"Bouvet Island\" >Bouvet Island<\/option><option value=\"Brazil\" >Brazil<\/option><option value=\"British Indian Ocean Territory\" >British Indian Ocean Territory<\/option><option value=\"Brunei Darussalam\" >Brunei Darussalam<\/option><option value=\"Bulgaria\" >Bulgaria<\/option><option value=\"Burkina Faso\" >Burkina Faso<\/option><option value=\"Burundi\" >Burundi<\/option><option value=\"Cabo Verde\" >Cabo Verde<\/option><option value=\"Cambodia\" >Cambodia<\/option><option value=\"Cameroon\" >Cameroon<\/option><option value=\"Canada\" >Canada<\/option><option value=\"Cayman Islands\" >Cayman Islands<\/option><option value=\"Central African Republic\" >Central African Republic<\/option><option value=\"Chad\" >Chad<\/option><option value=\"Chile\" >Chile<\/option><option value=\"China\" >China<\/option><option value=\"Christmas Island\" >Christmas Island<\/option><option value=\"Cocos (Keeling) Islands\" >Cocos (Keeling) Islands<\/option><option value=\"Colombia\" >Colombia<\/option><option value=\"Comoros\" >Comoros<\/option><option value=\"Congo\" >Congo<\/option><option value=\"Congo (Democratic Republic of the)\" >Congo (Democratic Republic of the)<\/option><option value=\"Cook Islands\" >Cook Islands<\/option><option value=\"Costa Rica\" >Costa Rica<\/option><option value=\"Croatia\" >Croatia<\/option><option value=\"Cuba\" >Cuba<\/option><option value=\"Cura\u00e7ao\" >Cura\u00e7ao<\/option><option value=\"Cyprus\" >Cyprus<\/option><option value=\"Czech Republic\" >Czech Republic<\/option><option value=\"C\u00f4te d&#039;Ivoire\" >C\u00f4te d&#039;Ivoire<\/option><option value=\"Denmark\" >Denmark<\/option><option value=\"Djibouti\" >Djibouti<\/option><option value=\"Dominica\" >Dominica<\/option><option value=\"Dominican Republic\" >Dominican Republic<\/option><option value=\"Ecuador\" >Ecuador<\/option><option value=\"Egypt\" >Egypt<\/option><option value=\"El Salvador\" >El Salvador<\/option><option value=\"Equatorial Guinea\" >Equatorial Guinea<\/option><option value=\"Eritrea\" >Eritrea<\/option><option value=\"Estonia\" >Estonia<\/option><option value=\"Eswatini (Kingdom of)\" >Eswatini (Kingdom of)<\/option><option value=\"Ethiopia\" >Ethiopia<\/option><option value=\"Falkland Islands (Malvinas)\" >Falkland Islands (Malvinas)<\/option><option value=\"Faroe Islands\" >Faroe Islands<\/option><option value=\"Fiji\" >Fiji<\/option><option value=\"Finland\" >Finland<\/option><option value=\"France\" >France<\/option><option value=\"French Guiana\" >French Guiana<\/option><option value=\"French Polynesia\" >French Polynesia<\/option><option value=\"French Southern Territories\" >French Southern Territories<\/option><option value=\"Gabon\" >Gabon<\/option><option value=\"Gambia\" >Gambia<\/option><option value=\"Georgia\" >Georgia<\/option><option value=\"Germany\" >Germany<\/option><option value=\"Ghana\" >Ghana<\/option><option value=\"Gibraltar\" >Gibraltar<\/option><option value=\"Greece\" >Greece<\/option><option value=\"Greenland\" >Greenland<\/option><option value=\"Grenada\" >Grenada<\/option><option value=\"Guadeloupe\" >Guadeloupe<\/option><option value=\"Guam\" >Guam<\/option><option value=\"Guatemala\" >Guatemala<\/option><option value=\"Guernsey\" >Guernsey<\/option><option value=\"Guinea\" >Guinea<\/option><option value=\"Guinea-Bissau\" >Guinea-Bissau<\/option><option value=\"Guyana\" >Guyana<\/option><option value=\"Haiti\" >Haiti<\/option><option value=\"Heard Island and McDonald Islands\" >Heard Island and McDonald Islands<\/option><option value=\"Honduras\" >Honduras<\/option><option value=\"Hong Kong\" >Hong Kong<\/option><option value=\"Hungary\" >Hungary<\/option><option value=\"Iceland\" >Iceland<\/option><option value=\"India\" >India<\/option><option value=\"Indonesia\" >Indonesia<\/option><option value=\"Iran (Islamic Republic of)\" >Iran (Islamic Republic of)<\/option><option value=\"Iraq\" >Iraq<\/option><option value=\"Ireland (Republic of)\" >Ireland (Republic of)<\/option><option value=\"Isle of Man\" >Isle of Man<\/option><option value=\"Israel\" >Israel<\/option><option value=\"Italy\" >Italy<\/option><option value=\"Jamaica\" >Jamaica<\/option><option value=\"Japan\" >Japan<\/option><option value=\"Jersey\" >Jersey<\/option><option value=\"Jordan\" >Jordan<\/option><option value=\"Kazakhstan\" >Kazakhstan<\/option><option value=\"Kenya\" >Kenya<\/option><option value=\"Kiribati\" >Kiribati<\/option><option value=\"Korea (Democratic People&#039;s Republic of)\" >Korea (Democratic People&#039;s Republic of)<\/option><option value=\"Korea (Republic of)\" >Korea (Republic of)<\/option><option value=\"Kosovo\" >Kosovo<\/option><option value=\"Kuwait\" >Kuwait<\/option><option value=\"Kyrgyzstan\" >Kyrgyzstan<\/option><option value=\"Lao People&#039;s Democratic Republic\" >Lao People&#039;s Democratic Republic<\/option><option value=\"Latvia\" >Latvia<\/option><option value=\"Lebanon\" >Lebanon<\/option><option value=\"Lesotho\" >Lesotho<\/option><option value=\"Liberia\" >Liberia<\/option><option value=\"Libya\" >Libya<\/option><option value=\"Liechtenstein\" >Liechtenstein<\/option><option value=\"Lithuania\" >Lithuania<\/option><option value=\"Luxembourg\" >Luxembourg<\/option><option value=\"Macao\" >Macao<\/option><option value=\"Madagascar\" >Madagascar<\/option><option value=\"Malawi\" >Malawi<\/option><option value=\"Malaysia\" >Malaysia<\/option><option value=\"Maldives\" >Maldives<\/option><option value=\"Mali\" >Mali<\/option><option value=\"Malta\" >Malta<\/option><option value=\"Marshall Islands\" >Marshall Islands<\/option><option value=\"Martinique\" >Martinique<\/option><option value=\"Mauritania\" >Mauritania<\/option><option value=\"Mauritius\" >Mauritius<\/option><option value=\"Mayotte\" >Mayotte<\/option><option value=\"Mexico\" >Mexico<\/option><option value=\"Micronesia (Federated States of)\" >Micronesia (Federated States of)<\/option><option value=\"Moldova (Republic of)\" >Moldova (Republic of)<\/option><option value=\"Monaco\" >Monaco<\/option><option value=\"Mongolia\" >Mongolia<\/option><option value=\"Montenegro\" >Montenegro<\/option><option value=\"Montserrat\" >Montserrat<\/option><option value=\"Morocco\" >Morocco<\/option><option value=\"Mozambique\" >Mozambique<\/option><option value=\"Myanmar\" >Myanmar<\/option><option value=\"Namibia\" >Namibia<\/option><option value=\"Nauru\" >Nauru<\/option><option value=\"Nepal\" >Nepal<\/option><option value=\"Netherlands\" >Netherlands<\/option><option value=\"New Caledonia\" >New Caledonia<\/option><option value=\"New Zealand\" >New Zealand<\/option><option value=\"Nicaragua\" >Nicaragua<\/option><option value=\"Niger\" >Niger<\/option><option value=\"Nigeria\" >Nigeria<\/option><option value=\"Niue\" >Niue<\/option><option value=\"Norfolk Island\" >Norfolk Island<\/option><option value=\"North Macedonia (Republic of)\" >North Macedonia (Republic of)<\/option><option value=\"Northern Mariana Islands\" >Northern Mariana Islands<\/option><option value=\"Norway\" >Norway<\/option><option value=\"Oman\" >Oman<\/option><option value=\"Pakistan\" >Pakistan<\/option><option value=\"Palau\" >Palau<\/option><option value=\"Palestine (State of)\" >Palestine (State of)<\/option><option value=\"Panama\" >Panama<\/option><option value=\"Papua New Guinea\" >Papua New Guinea<\/option><option value=\"Paraguay\" >Paraguay<\/option><option value=\"Peru\" >Peru<\/option><option value=\"Philippines\" >Philippines<\/option><option value=\"Pitcairn\" >Pitcairn<\/option><option value=\"Poland\" >Poland<\/option><option value=\"Portugal\" >Portugal<\/option><option value=\"Puerto Rico\" >Puerto Rico<\/option><option value=\"Qatar\" >Qatar<\/option><option value=\"Romania\" >Romania<\/option><option value=\"Russian Federation\" >Russian Federation<\/option><option value=\"Rwanda\" >Rwanda<\/option><option value=\"R\u00e9union\" >R\u00e9union<\/option><option value=\"Saint Barth\u00e9lemy\" >Saint Barth\u00e9lemy<\/option><option value=\"Saint Helena, Ascension and Tristan da Cunha\" >Saint Helena, Ascension and Tristan da Cunha<\/option><option value=\"Saint Kitts and Nevis\" >Saint Kitts and Nevis<\/option><option value=\"Saint Lucia\" >Saint Lucia<\/option><option value=\"Saint Martin (French part)\" >Saint Martin (French part)<\/option><option value=\"Saint Pierre and Miquelon\" >Saint Pierre and Miquelon<\/option><option value=\"Saint Vincent and the Grenadines\" >Saint Vincent and the Grenadines<\/option><option value=\"Samoa\" >Samoa<\/option><option value=\"San Marino\" >San Marino<\/option><option value=\"Sao Tome and Principe\" >Sao Tome and Principe<\/option><option value=\"Saudi Arabia\" >Saudi Arabia<\/option><option value=\"Senegal\" >Senegal<\/option><option value=\"Serbia\" >Serbia<\/option><option value=\"Seychelles\" >Seychelles<\/option><option value=\"Sierra Leone\" >Sierra Leone<\/option><option value=\"Singapore\" >Singapore<\/option><option value=\"Sint Maarten (Dutch part)\" >Sint Maarten (Dutch part)<\/option><option value=\"Slovakia\" >Slovakia<\/option><option value=\"Slovenia\" >Slovenia<\/option><option value=\"Solomon Islands\" >Solomon Islands<\/option><option value=\"Somalia\" >Somalia<\/option><option value=\"South Africa\" >South Africa<\/option><option value=\"South Georgia and the South Sandwich Islands\" >South Georgia and the South Sandwich Islands<\/option><option value=\"South Sudan\" >South Sudan<\/option><option value=\"Spain\" >Spain<\/option><option value=\"Sri Lanka\" >Sri Lanka<\/option><option value=\"Sudan\" >Sudan<\/option><option value=\"Suriname\" >Suriname<\/option><option value=\"Svalbard and Jan Mayen\" >Svalbard and Jan Mayen<\/option><option value=\"Sweden\" >Sweden<\/option><option value=\"Switzerland\" >Switzerland<\/option><option value=\"Syrian Arab Republic\" >Syrian Arab Republic<\/option><option value=\"Taiwan, Province of China\" >Taiwan, Province of China<\/option><option value=\"Tajikistan\" >Tajikistan<\/option><option value=\"Tanzania (United Republic of)\" >Tanzania (United Republic of)<\/option><option value=\"Thailand\" >Thailand<\/option><option value=\"Timor-Leste\" >Timor-Leste<\/option><option value=\"Togo\" >Togo<\/option><option value=\"Tokelau\" >Tokelau<\/option><option value=\"Tonga\" >Tonga<\/option><option value=\"Trinidad and Tobago\" >Trinidad and Tobago<\/option><option value=\"Tunisia\" >Tunisia<\/option><option value=\"Turkey\" >Turkey<\/option><option value=\"Turkmenistan\" >Turkmenistan<\/option><option value=\"Turks and Caicos Islands\" >Turks and Caicos Islands<\/option><option value=\"Tuvalu\" >Tuvalu<\/option><option value=\"Uganda\" >Uganda<\/option><option value=\"Ukraine\" >Ukraine<\/option><option value=\"United Arab Emirates\" >United Arab Emirates<\/option><option value=\"United Kingdom of Great Britain and Northern Ireland\" >United Kingdom of Great Britain and Northern Ireland<\/option><option value=\"United States Minor Outlying Islands\" >United States Minor Outlying Islands<\/option><option value=\"United States of America\" >United States of America<\/option><option value=\"Uruguay\" >Uruguay<\/option><option value=\"Uzbekistan\" >Uzbekistan<\/option><option value=\"Vanuatu\" >Vanuatu<\/option><option value=\"Vatican City State\" >Vatican City State<\/option><option value=\"Venezuela (Bolivarian Republic of)\" >Venezuela (Bolivarian Republic of)<\/option><option value=\"Vietnam\" >Vietnam<\/option><option value=\"Virgin Islands (British)\" >Virgin Islands (British)<\/option><option value=\"Virgin Islands (U.S.)\" >Virgin Islands (U.S.)<\/option><option value=\"Wallis and Futuna\" >Wallis and Futuna<\/option><option value=\"Western Sahara\" >Western Sahara<\/option><option value=\"Yemen\" >Yemen<\/option><option value=\"Zambia\" >Zambia<\/option><option value=\"Zimbabwe\" >Zimbabwe<\/option><option value=\"\u00c5land Islands\" >\u00c5land Islands<\/option><\/select><\/div><div id=\"wpforms-6000-field_7-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"7\"><div class=\"wpforms-clear wpforms-pagebreak-left\"><\/div><\/div><\/div><\/div><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha\" style=\"display:none;\"><div class=\"g-recaptcha\" data-sitekey=\"6LdvKC4UAAAAAIhwyHyxJojmkYtpcF910ywVHAgb\"><\/div><input type=\"text\" name=\"g-recaptcha-hidden\" class=\"wpforms-recaptcha-hidden\" style=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\" required><\/div><div class=\"wpforms-submit-container\" style=\"display:none;\"><input type=\"hidden\" name=\"wpforms[id]\" value=\"6000\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" class=\"wpforms-submit \" id=\"wpforms-submit-6000\" value=\"wpforms-submit\" aria-live=\"assertive\" data-alt-text=\"Submitting Access Information...\" data-submit-text=\"Request Access\">Request Access<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mericonline.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u062d\u0627\u0641\u0638 \u0639\u0644\u0649 \u0627\u062a\u0635\u0627\u0644 \u0645\u0624\u0633\u0633\u062a\u0643 \u0648\u0623\u0645\u0627\u0646\u0647\u0627 \u0648\u0633\u0644\u0627\u0645\u062a\u0647\u0627 \u0646\u062d\u0646 \u0646\u0636\u0645\u0646 \u0634\u0628\u0643\u0627\u062a \u0627\u062c\u062a\u0645\u0627\u0639\u064a\u0629 \u0622\u0645\u0646\u0629 \u062a\u0642\u062a\u0635\u0631 \u0639\u0644\u0649 \u0627\u0644\u0623\u0641\u0631\u0627\u062f \u0641\u064a \u0645\u0624\u0633\u0633\u062a\u0643. \u062a\u0634\u0628\u0647 \u0628\u0648\u0627\u0628\u0627\u062a \u0634\u0628\u0643\u062a\u0646\u0627 \u0627\u0644\u0627\u062c\u062a\u0645\u0627\u0639\u064a\u0629 \u0642\u0646\u0648\u0627\u062a \u0627\u0644\u062a\u0648\u0627\u0635\u0644 \u0627\u0644\u0627\u062c\u062a\u0645\u0627\u0639\u064a \u0627\u0644\u0639\u0627\u062f\u064a\u0629 \u0648\u0644\u0643\u0646\u0647\u0627 \u0623\u0643\u062b\u0631 \u0623\u0645\u0627\u0646\u064b\u0627 \u0648\u0633\u0631\u064a\u0629 \u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0645\u0624\u0633\u0633\u062a\u0643. \u062a\u0633\u0627\u0639\u062f \u0634\u0628\u0643\u0627\u062a \u0627\u0644\u062a\u0648\u0627\u0635\u0644 \u0627\u0644\u0627\u062c\u062a\u0645\u0627\u0639\u064a \u0639\u0644\u0649 \u062a\u0633\u0647\u064a\u0644 \u0627\u0644\u062a\u0648\u0627\u0635\u0644 \u0648\u0632\u064a\u0627\u062f\u0629 \u0627\u0644\u0631\u0648\u062d \u0627\u0644\u0645\u0639\u0646\u0648\u064a\u0629 \u0648\u0625\u0646\u062a\u0627\u062c\u064a\u0629 \u0627\u0644\u0645\u0648\u0638\u0641\u064a\u0646\u060c \u0644\u0630\u0644\u0643\u061b \u0627\u062d\u062a\u0641\u0638 \u0628\u0634\u0631\u0643\u062a\u0643 \u0623\u0648\u2026<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_analytify_skip_tracking":false,"footnotes":""},"class_list":["post-6473","page","type-page","status-publish","hentry","no-post-thumbnail"],"acf":[],"_links":{"self":[{"href":"https:\/\/mericonline.com\/ar\/wp-json\/wp\/v2\/pages\/6473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mericonline.com\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mericonline.com\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mericonline.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mericonline.com\/ar\/wp-json\/wp\/v2\/comments?post=6473"}],"version-history":[{"count":10,"href":"https:\/\/mericonline.com\/ar\/wp-json\/wp\/v2\/pages\/6473\/revisions"}],"predecessor-version":[{"id":6669,"href":"https:\/\/mericonline.com\/ar\/wp-json\/wp\/v2\/pages\/6473\/revisions\/6669"}],"wp:attachment":[{"href":"https:\/\/mericonline.com\/ar\/wp-json\/wp\/v2\/media?parent=6473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}